{"id":304085,"date":"2026-07-07T19:49:42","date_gmt":"2026-07-07T17:49:42","guid":{"rendered":"https:\/\/premium-homes.ch\/immobilien\/1771081it-mehrgenerationenhaus-mit-herz\/"},"modified":"2026-09-02T01:32:43","modified_gmt":"2026-09-01T23:32:43","slug":"1771081it-mehrgenerationenhaus-mit-herz","status":"publish","type":"casawp_property","link":"https:\/\/premium-homes.ch\/it\/immobilien\/1771081it-mehrgenerationenhaus-mit-herz\/","title":{"rendered":"MEHRGENERATIONENHAUS MIT HERZ"},"content":{"rendered":"<p>Dieses grossz\u00fcgige Generationenhaus \u00fcberzeugt auf den ersten Blick durch viel Raum, helle Wohnbereiche und eine ruhige, sonnige Lage. Die offene Raumwirkung, hohen Decken und warmen Materialien schaffen eine angenehme Wohnatmosph\u00e4re, w\u00e4hrend mehrere Balkone den Blick ins Gr\u00fcne \u00f6ffnen. <\/p>\n<p>Die Liegenschaft bietet vielseitige Nutzungsm\u00f6glichkeiten und eignet sich ideal f\u00fcr Familien, Mehrgenerationenwohnen oder individuelle Wohnkonzepte. Die Kombination aus Privatsph\u00e4re, Natur und guter Erreichbarkeit macht dieses Objekt zu einer seltenen Gelegenheit f\u00fcr K\u00e4ufer, die Wert auf Wohnqualit\u00e4t und Grossz\u00fcgigkeit legen.<\/p>\n<p>Die Anbindung an \u00f6ffentliche Verkehrsmittel und die N\u00e4he zu Einkaufsm\u00f6glichkeiten gew\u00e4hrleisten eine hohe Lebensqualit\u00e4t. Hier finden Sie einen R\u00fcckzugsort, der Komfort und Naturn\u00e4he harmonisch verbindet. Hier werden also keine W\u00fcnsche offen gelassen. Profitieren Sie und \u00fcberzeugen Sie sich selbst! Dieses PREMIUM HOMES Angebot bietet:<\/p>\n<ul>\n<li>Generationenhaus mit Charakter<\/li>\n<li>Historischer Charme<\/li>\n<li>Umfassend renoviert (2022)<\/li>\n<li>Helle R\u00e4umlichkeiten<\/li>\n<li>Durchdachter Grundriss<\/li>\n<li>Familienfreundliches Quartier<\/li>\n<li>Vielseitige Nutzungsm\u00f6glichkeiten<\/li>\n<li>Einmalige Investitionsm\u00f6glichkeit<\/li>\n<li>Potenzial f\u00fcr langfristige Projekte<\/li>\n<li>Zahlreiche Nutzungsvariationen<\/li>\n<li>Nettowohnfl\u00e4che 155 m\u00b2<\/li>\n<li>Bruttowohnfl\u00e4che 182 m\u00b2<\/li>\n<li>Stilvolle Wohnatmosph\u00e4re<\/li>\n<\/ul>\n<p>Interessiert? Gerne f\u00fchren wir Sie durch eine unverbindliche Besichtigung! Sie wollen Ihr Haus oder Ihre Wohnung sorgenfrei verkaufen? Wir sagen Ihnen den aktuellen Marktwert Ihrer Immobilie, diskret und unverbindlich! Haben Sie Interesse an einem ersten unverbindlichen Gedankenaustausch? Z\u00f6gern Sie nicht und kontaktieren Sie uns. Wir freuen uns auf Sie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dieses grossz\u00fcgige Generationenhaus \u00fcberzeugt auf den ersten Blick durch viel Raum, helle Wohnbereiche und eine ruhige, sonnige Lage. Die offene Raumwirkung, hohen Decken und warmen Materialien scha \u2026<\/p>\n","protected":false},"author":0,"featured_media":304086,"parent":0,"menu_order":149,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"casawp_category":[696],"casawp_feature":[697,747],"casawp_utility":[699],"casawp_location":[702,712,1002],"casawp_salestype":[700],"casawp_availability":[701],"casawp_region":[],"class_list":["post-304085","casawp_property","type-casawp_property","status-publish","has-post-thumbnail","hentry","casawp_category-single-house","casawp_feature-has-parking","casawp_feature-has-balcony","casawp_utility-residential","casawp_location-country_ch","casawp_location-region_sg","casawp_location-locality_st-josefen","casawp_salestype-buy","casawp_availability-active"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MEHRGENERATIONENHAUS MIT HERZ - PREMIUM HOMES AG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/premium-homes.ch\/it\/immobilien\/1771081it-mehrgenerationenhaus-mit-herz\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MEHRGENERATIONENHAUS MIT HERZ - PREMIUM HOMES AG\" \/>\n<meta property=\"og:description\" content=\"Dieses grossz\u00fcgige Generationenhaus \u00fcberzeugt auf den ersten Blick durch viel Raum, helle Wohnbereiche und eine ruhige, sonnige Lage. Die offene Raumwirkung, hohen Decken und warmen Materialien scha \u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/premium-homes.ch\/it\/immobilien\/1771081it-mehrgenerationenhaus-mit-herz\/\" \/>\n<meta property=\"og:site_name\" content=\"PREMIUM HOMES AG\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PREMIUMHOMESAG\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T23:32:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/premium-homes.ch\\\/it\\\/immobilien\\\/1771081it-mehrgenerationenhaus-mit-herz\\\/\",\"url\":\"https:\\\/\\\/premium-homes.ch\\\/it\\\/immobilien\\\/1771081it-mehrgenerationenhaus-mit-herz\\\/\",\"name\":\"MEHRGENERATIONENHAUS MIT HERZ - PREMIUM HOMES AG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/premium-homes.ch\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/premium-homes.ch\\\/it\\\/immobilien\\\/1771081it-mehrgenerationenhaus-mit-herz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/premium-homes.ch\\\/it\\\/immobilien\\\/1771081it-mehrgenerationenhaus-mit-herz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.casasoft.com\\\/media\\\/provider-11189\\\/property-1694947\\\/A574DAB438F998C19B3D892B84036366FCB6D0D0.jpeg?p=xl\",\"datePublished\":\"2026-07-07T17:49:42+00:00\",\"dateModified\":\"2026-09-01T23:32:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/premium-homes.ch\\\/it\\\/immobilien\\\/1771081it-mehrgenerationenhaus-mit-herz\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/premium-homes.ch\\\/it\\\/immobilien\\\/1771081it-mehrgenerationenhaus-mit-herz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/premium-homes.ch\\\/it\\\/immobilien\\\/1771081it-mehrgenerationenhaus-mit-herz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.casasoft.com\\\/media\\\/provider-11189\\\/property-1694947\\\/A574DAB438F998C19B3D892B84036366FCB6D0D0.jpeg?p=xl\",\"contentUrl\":\"https:\\\/\\\/cdn.casasoft.com\\\/media\\\/provider-11189\\\/property-1694947\\\/A574DAB438F998C19B3D892B84036366FCB6D0D0.jpeg?p=xl\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/premium-homes.ch\\\/it\\\/immobilien\\\/1771081it-mehrgenerationenhaus-mit-herz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/premium-homes.ch\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Propriet\u00e0\",\"item\":\"https:\\\/\\\/premium-homes.ch\\\/it\\\/immobilien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MEHRGENERATIONENHAUS MIT HERZ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/premium-homes.ch\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/premium-homes.ch\\\/it\\\/\",\"name\":\"PREMIUM HOMES AG\",\"description\":\"PREMIUM HOMES AG in Gerlafingen und Baar\",\"publisher\":{\"@id\":\"https:\\\/\\\/premium-homes.ch\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/premium-homes.ch\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/premium-homes.ch\\\/it\\\/#organization\",\"name\":\"PREMIUM HOMES AG\",\"url\":\"https:\\\/\\\/premium-homes.ch\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/premium-homes.ch\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/premium-homes.ch\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/premium-homes.ch\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-1.svg\",\"width\":1,\"height\":1,\"caption\":\"PREMIUM HOMES AG\"},\"image\":{\"@id\":\"https:\\\/\\\/premium-homes.ch\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PREMIUMHOMESAG\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/premium-homes-ag\\\/\",\"https:\\\/\\\/www.instagram.com\\\/premiumhomesag\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@premiumhomesag\",\"https:\\\/\\\/www.youtube.com\\\/@premiumhomesag73\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MEHRGENERATIONENHAUS MIT HERZ - PREMIUM HOMES AG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/premium-homes.ch\/it\/immobilien\/1771081it-mehrgenerationenhaus-mit-herz\/","og_locale":"it_IT","og_type":"article","og_title":"MEHRGENERATIONENHAUS MIT HERZ - PREMIUM HOMES AG","og_description":"Dieses grossz\u00fcgige Generationenhaus \u00fcberzeugt auf den ersten Blick durch viel Raum, helle Wohnbereiche und eine ruhige, sonnige Lage. Die offene Raumwirkung, hohen Decken und warmen Materialien scha \u2026","og_url":"https:\/\/premium-homes.ch\/it\/immobilien\/1771081it-mehrgenerationenhaus-mit-herz\/","og_site_name":"PREMIUM HOMES AG","article_publisher":"https:\/\/www.facebook.com\/PREMIUMHOMESAG\/","article_modified_time":"2026-09-01T23:32:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/premium-homes.ch\/it\/immobilien\/1771081it-mehrgenerationenhaus-mit-herz\/","url":"https:\/\/premium-homes.ch\/it\/immobilien\/1771081it-mehrgenerationenhaus-mit-herz\/","name":"MEHRGENERATIONENHAUS MIT HERZ - PREMIUM HOMES AG","isPartOf":{"@id":"https:\/\/premium-homes.ch\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/premium-homes.ch\/it\/immobilien\/1771081it-mehrgenerationenhaus-mit-herz\/#primaryimage"},"image":{"@id":"https:\/\/premium-homes.ch\/it\/immobilien\/1771081it-mehrgenerationenhaus-mit-herz\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.casasoft.com\/media\/provider-11189\/property-1694947\/A574DAB438F998C19B3D892B84036366FCB6D0D0.jpeg?p=xl","datePublished":"2026-07-07T17:49:42+00:00","dateModified":"2026-09-01T23:32:43+00:00","breadcrumb":{"@id":"https:\/\/premium-homes.ch\/it\/immobilien\/1771081it-mehrgenerationenhaus-mit-herz\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/premium-homes.ch\/it\/immobilien\/1771081it-mehrgenerationenhaus-mit-herz\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/premium-homes.ch\/it\/immobilien\/1771081it-mehrgenerationenhaus-mit-herz\/#primaryimage","url":"https:\/\/cdn.casasoft.com\/media\/provider-11189\/property-1694947\/A574DAB438F998C19B3D892B84036366FCB6D0D0.jpeg?p=xl","contentUrl":"https:\/\/cdn.casasoft.com\/media\/provider-11189\/property-1694947\/A574DAB438F998C19B3D892B84036366FCB6D0D0.jpeg?p=xl"},{"@type":"BreadcrumbList","@id":"https:\/\/premium-homes.ch\/it\/immobilien\/1771081it-mehrgenerationenhaus-mit-herz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/premium-homes.ch\/it\/"},{"@type":"ListItem","position":2,"name":"Propriet\u00e0","item":"https:\/\/premium-homes.ch\/it\/immobilien\/"},{"@type":"ListItem","position":3,"name":"MEHRGENERATIONENHAUS MIT HERZ"}]},{"@type":"WebSite","@id":"https:\/\/premium-homes.ch\/it\/#website","url":"https:\/\/premium-homes.ch\/it\/","name":"PREMIUM HOMES AG","description":"PREMIUM HOMES AG in Gerlafingen und Baar","publisher":{"@id":"https:\/\/premium-homes.ch\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/premium-homes.ch\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/premium-homes.ch\/it\/#organization","name":"PREMIUM HOMES AG","url":"https:\/\/premium-homes.ch\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/premium-homes.ch\/it\/#\/schema\/logo\/image\/","url":"https:\/\/premium-homes.ch\/wp-content\/uploads\/2025\/11\/logo-1.svg","contentUrl":"https:\/\/premium-homes.ch\/wp-content\/uploads\/2025\/11\/logo-1.svg","width":1,"height":1,"caption":"PREMIUM HOMES AG"},"image":{"@id":"https:\/\/premium-homes.ch\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PREMIUMHOMESAG\/","https:\/\/www.linkedin.com\/company\/premium-homes-ag\/","https:\/\/www.instagram.com\/premiumhomesag\/","https:\/\/www.tiktok.com\/@premiumhomesag","https:\/\/www.youtube.com\/@premiumhomesag73"]}]}},"_links":{"self":[{"href":"https:\/\/premium-homes.ch\/it\/wp-json\/wp\/v2\/casawp_property\/304085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/premium-homes.ch\/it\/wp-json\/wp\/v2\/casawp_property"}],"about":[{"href":"https:\/\/premium-homes.ch\/it\/wp-json\/wp\/v2\/types\/casawp_property"}],"replies":[{"embeddable":true,"href":"https:\/\/premium-homes.ch\/it\/wp-json\/wp\/v2\/comments?post=304085"}],"version-history":[{"count":0,"href":"https:\/\/premium-homes.ch\/it\/wp-json\/wp\/v2\/casawp_property\/304085\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/premium-homes.ch\/it\/wp-json\/wp\/v2\/media\/304086"}],"wp:attachment":[{"href":"https:\/\/premium-homes.ch\/it\/wp-json\/wp\/v2\/media?parent=304085"}],"wp:term":[{"taxonomy":"casawp_category","embeddable":true,"href":"https:\/\/premium-homes.ch\/it\/wp-json\/wp\/v2\/casawp_category?post=304085"},{"taxonomy":"casawp_feature","embeddable":true,"href":"https:\/\/premium-homes.ch\/it\/wp-json\/wp\/v2\/casawp_feature?post=304085"},{"taxonomy":"casawp_utility","embeddable":true,"href":"https:\/\/premium-homes.ch\/it\/wp-json\/wp\/v2\/casawp_utility?post=304085"},{"taxonomy":"casawp_location","embeddable":true,"href":"https:\/\/premium-homes.ch\/it\/wp-json\/wp\/v2\/casawp_location?post=304085"},{"taxonomy":"casawp_salestype","embeddable":true,"href":"https:\/\/premium-homes.ch\/it\/wp-json\/wp\/v2\/casawp_salestype?post=304085"},{"taxonomy":"casawp_availability","embeddable":true,"href":"https:\/\/premium-homes.ch\/it\/wp-json\/wp\/v2\/casawp_availability?post=304085"},{"taxonomy":"casawp_region","embeddable":true,"href":"https:\/\/premium-homes.ch\/it\/wp-json\/wp\/v2\/casawp_region?post=304085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}